{"id":19511,"date":"2025-08-07T05:28:04","date_gmt":"2025-08-07T05:28:04","guid":{"rendered":"http:\/\/d4700774-6bea-4c81-81d1-3dcb0e1fd574"},"modified":"2025-08-07T05:28:04","modified_gmt":"2025-08-07T05:28:04","slug":"quanto-tempo-apos-a-morte-pode-requerer-pensao-por-morte","status":"publish","type":"post","link":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/quanto-tempo-apos-a-morte-pode-requerer-pensao-por-morte\/","title":{"rendered":"Quanto tempo ap\u00f3s a morte pode requerer pens\u00e3o por morte"},"content":{"rendered":"\n\n<h2 class=\"wp-block-heading\">Quanto tempo ap\u00f3s a morte pode entrar com pedido de pens\u00e3o?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Pode pedir pens\u00e3o por morte depois de 10 anos?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A obriga\u00e7\u00e3o \u00e9 do INSS, n\u00e3o do benefici\u00e1rio. O aposentado com mais de 10 anos n\u00e3o poder\u00e1 requerer a revis\u00e3o de sua aposentadoria, e isso vale para o INSS. Chamamos este prazo de decadencial.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual a car\u00eancia para receber pens\u00e3o por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>N\u00e3o h\u00e1 car\u00eancia para a pens\u00e3o por morte, ou seja, o segurado falecido n\u00e3o precisa ter cumprido um per\u00edodo m\u00ednimo de contribui\u00e7\u00f5es para que seus dependentes recebam o benef\u00edcio.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prazo para o INSS analisar pens\u00e3o por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os pedidos de benef\u00edcios seguem a mesma l\u00f3gica: prazo de 30 dias para processos envolvendo sal\u00e1rio-maternidade e pens\u00e3o por morte e de 60 dias para os que tratem de aux\u00edlio-doen\u00e7a. Ultrapassados os prazos, o benef\u00edcio dever\u00e1 ser imediatamente concedido.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual o tempo m\u00e1ximo para solicitar pens\u00e3o por morte?<\/h2>\n\n<p class=\"wp-block-paragraph\">Idade do dependente (c\u00f4njuge, companheiro ou companheira): | Per\u00edodo que receber\u00e1 a pens\u00e3o por morte:<\/p><table border=\"1\"><tr><td>Entre 28 a 30 anos de idade<\/td><td>10 anos<\/td><\/tr><tr><td>Entre 31 e 41 anos de idade<\/td><td>15 anos<\/td><\/tr><tr><td>Entre 42 a 44 anos de idade<\/td><td>20 anos<\/td><\/tr><tr><td>Mais de 45 anos<\/td><td>Vital\u00edcia<\/td><\/tr><\/table><br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o prazo para dar entrada na solicita\u00e7\u00e3o de pens\u00e3o por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Prazo para requerer solicita\u00e7\u00e3o de pens\u00e3o por morte, sem preju\u00edzo de retroativos, ser\u00e1 de at\u00e9 90 (noventa) dias para todos com exce\u00e7\u00e3o do prazo de 180 (cento e oitenta) dias para os menores de 16 anos, ambos contados a partir da data do \u00f3bito.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Pode pedir pens\u00e3o por morte depois de dois anos do \u00f3bito?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A resposta \u00e9 sim, \u00e9 poss\u00edvel requerer a pens\u00e3o por morte, independentemente do tempo que tenha se passado desde o falecimento. Contudo, h\u00e1 algumas particularidades importantes a serem observadas. III &#8211; da decis\u00e3o judicial, no caso de morte presumida.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prazo prescricional para requerer pens\u00e3o por morte?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prazo m\u00e1ximo para requerer pens\u00e3o por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Prazo para requerer solicita\u00e7\u00e3o de pens\u00e3o por morte, sem preju\u00edzo de retroativos, ser\u00e1 de at\u00e9 90 (noventa) dias para todos com exce\u00e7\u00e3o do prazo de 180 (cento e oitenta) dias para os menores de 16 anos, ambos contados a partir da data do \u00f3bito.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o prazo para requerer a pens\u00e3o por morte sem perder o direito aos atrasados?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>O prazo \u00e9 de 90 dias ap\u00f3s o \u00f3bito. Ap\u00f3s esse prazo, o INSS s\u00f3 pagar\u00e1 o benef\u00edcio a partir da data do pedido, n\u00e3o retroagindo \u00e0 data da morte.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Tem como pedir pens\u00e3o por morte retroativa?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Assim, se a pens\u00e3o for solicitada em at\u00e9 90 dias ap\u00f3s o \u00f3bito, o pagamento do benef\u00edcio vai ser retroativo \u00e0 data da morte do segurado. Uma informa\u00e7\u00e3o importante \u00e9 que essa regra n\u00e3o inclui os dependentes menores de 16 anos e os considerados incapazes para a vida civil.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quanto tempo prescreve o pedido de pens\u00e3o por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A pretens\u00e3o ao direito para o reconhecimento do benef\u00edcio de pens\u00e3o por morte \u00e9 imprescrit\u00edvel; mas prescrevem as parcelas vencidas do benef\u00edcio anteriores a cinco anos &#8211; prescri\u00e7\u00e3o quinquenal &#8211; da data do requerimento administrativo, conforme jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ).<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as novas regras para pens\u00e3o por morte?<\/h2>\n\nA pens\u00e3o vai de quatro meses a vital\u00edcia, com dura\u00e7\u00e3o vari\u00e1vel conforme o tempo de contribui\u00e7\u00e3o da pessoa falecida, tempo da uni\u00e3o e idade do vi\u00favo. Tempo de contribui\u00e7\u00e3o: se a pessoa que faleceu tinha menos de 18 contribui\u00e7\u00f5es mensais antes do \u00f3bito, a dura\u00e7\u00e3o da pens\u00e3o para o vi\u00favo ser\u00e1 de quatro meses.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a nova regra do INSS 2025?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>O ajuste da idade ser\u00e1 feito na aposentadoria por tempo de contribui\u00e7\u00e3o &#8211; transi\u00e7\u00e3o por idade, que a cada ano acrescenta 6 meses at\u00e9 atingir a idade de 62 anos para mulher e 65 anos para o homem.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Pode pedir pens\u00e3o por morte depois de 5 anos?<\/h2>\n\nCom rela\u00e7\u00e3o ao prazo para pedir a pens\u00e3o, os dependentes do segurado que faleceu t\u00eam de solicitar o benef\u00edcio em at\u00e9 90 dias ap\u00f3s a morte, para ter direito a receber desde a data do \u00f3bito. O prazo \u00e9 maior para os filhos menores de 16 anos, que t\u00eam at\u00e9 180 dias para fazer a solicita\u00e7\u00e3o.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prazo para comunicar o falecimento de uma pessoa ao INSS?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9 preciso informar o INSS sobre falecimento?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Tanto para quem tem direito \u00e0 pens\u00e3o quanto para aqueles que n\u00e3o t\u00eam, a solicita\u00e7\u00e3o do pagamento deve ser feita por meio do aplicativo Meu INSS ou pelo site do Instituto, na aba \u201cSolicitar valor n\u00e3o recebido at\u00e9 a data do \u00f3bito do benefici\u00e1rio\u201d.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quanto tempo para dar entrada no INSS por morte?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Ou seja, para ter direito \u00e0 Pens\u00e3o por Morte desde a data do \u00f3bito, os dependentes precisam requerer o benef\u00edcio em at\u00e9 90 dias do falecimento, exceto os filhos menores de 16 anos, que podem fazer tal pedido em at\u00e9 180 dias da data da morte do(a) segurado(a).<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Pode sacar o \u00faltimo benef\u00edcio do falecido?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\u00c9 importante esclarecer que, ap\u00f3s a morte do segurado, n\u00e3o se deve sacar os valores relativos a benef\u00edcios recebidos do INSS. Essa regra vale mesmo para os casos em que o falecimento gera direito \u00e0 pens\u00e3o por morte.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem comunica o \u00f3bito ao banco?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A obriga\u00e7\u00e3o \u00e9 dos Cart\u00f3rios em informar sobre os \u00f3bitos. Al\u00e9m disso, os bancos tamb\u00e9m dever\u00e3o devolver os valores que ocasionalmente forem depositados ap\u00f3s o \u00f3bito.<br \/>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Quanto tempo ap\u00f3s a morte pode entrar com pedido de pens\u00e3o? Pode pedir pens\u00e3o por morte depois de 10 anos? A obriga\u00e7\u00e3o \u00e9 do INSS, n\u00e3o do benefici\u00e1rio. O aposentado com mais de 10 anos n\u00e3o poder\u00e1 requerer a revis\u00e3o de sua aposentadoria, e isso vale para o INSS. Chamamos este prazo de decadencial. Qual [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19511","post","type-post","status-publish","format-standard","hentry","category-conteudo"],"_links":{"self":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/19511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=19511"}],"version-history":[{"count":1,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/19511\/revisions"}],"predecessor-version":[{"id":19512,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/19511\/revisions\/19512"}],"wp:attachment":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=19511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=19511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=19511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}