{"id":18929,"date":"2025-08-06T22:46:21","date_gmt":"2025-08-06T22:46:21","guid":{"rendered":"http:\/\/aa8fa0f5-4440-4b1d-859b-bedfcf10616b"},"modified":"2025-08-06T22:46:21","modified_gmt":"2025-08-06T22:46:21","slug":"recabitas-o-que-e-na-biblia","status":"publish","type":"post","link":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/recabitas-o-que-e-na-biblia\/","title":{"rendered":"Recabitas o que \u00e9 na b\u00edblia"},"content":{"rendered":"\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os recabitas segundo a B\u00edblia?<\/h2>\n\nEsse tipo de \u201cvolta ao passado\u201d ocorre v\u00e1rias vezes no livro de Jeremias. Jeremias 35 fala de um grupo de pessoas chamados recabitas. Eles viviam fora das cidades, em tendas, e nunca se fixavam num lugar.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem era o povo recabitas na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os recabitas eram um grupo de pessoas de um cl\u00e3 ou tribo dos queneus que habitavam em tendas e possu\u00edam regras estritas quanto ao consumo de bebidas alco\u00f3licas, mencionados principalmente em Jeremias 35. Os recabitas um grupo de pessoas origin\u00e1rias da regi\u00e3o de Midi\u00e3 e associadas aos israelitas.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual o erro dos recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A li\u00e7\u00e3o foi a seguinte: Os recabitas cumpriam fielmente as tradi\u00e7\u00f5es humanas, mas o povo de Jud\u00e1 n\u00e3o conseguia seguir os mandamentos do Deus vivo, mandamentos aos quais estavam associadas b\u00ean\u00e7\u00e3os reais e eternas.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o exemplo dos recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os recabitas n\u00e3o foram elogiados por Deus por recusarem beber vinho, nem por recusarem o estilo \u201cmoderno\u201d de vida. Eles foram tomados como exemplo por permanecerem fi\u00e9is, ao longo de s\u00e9culos, \u00e0s instru\u00e7\u00e3o de um dos seus ancestrais-fundadores.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Que significa a palavra recabitas?<\/h2>\n\nOs recabitas ( \/ \u02c8r\u025bk\u0259ba\u026ats \/ ) eram um cl\u00e3 b\u00edblico , descendentes de Recabe por meio de Jonadabe .<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que significa a palavra recabitas na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Esse tipo de \u201c volta ao passado \u201d ocorre v\u00e1rias vezes no livro de Jeremias. Jeremias 35 fala de um grupo de pessoas chamados recabitas. Eles viviam fora das cidades, em tendas, e nunca se fixavam num lugar.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem foram os povos recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os recabitas eram separatistas que se recusavam a participar de atividades agr\u00edcolas, beber vinho ou se envolver em outras pr\u00e1ticas associadas aos cananeus. Acreditando que o estilo de vida semin\u00f4made era uma obriga\u00e7\u00e3o religiosa, eles pastoreavam seus rebanhos por grande parte de Israel e Jud\u00e1.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que podemos aprender com os recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Essa observa\u00e7\u00e3o nos leva \u00e0s pr\u00f3ximas duas li\u00e7\u00f5es. A Li\u00e7\u00e3o 2 se baseia na qualidade excepcional da obedi\u00eancia dos descendentes recabitas ao seu ancestral Jonadabe. Isso \u00e9 enfatizado no texto quando Deus promete que eles ser\u00e3o recompensados por nunca deixarem de ter um homem para se apresentar diante dele.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Porque os recabitas n\u00e3o bebiam vinho?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Eles n\u00e3o bebem vinho porque obedecem \u00e0 ordem do seu antepassado.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi Jonadabe, filho de Recabe, na B\u00edblia?<\/h2>\n\nJonadabe (em hebraico: Y\u00f4n\u0101d\u0101b) ou Jeonadabe (em hebraico: Yeh\u00f4n\u0101d\u0101b, lit. &#8220;Jav\u00e9 est\u00e1 disposto&#8221; ou &#8220;nobre&#8221; ou &#8220;generoso&#8221;) foi um hebreu, filho de Recabe. Se encontrou com Je\u00fa por ocasi\u00e3o da aboli\u00e7\u00e3o do culto a Baal em Samaria e foi o fundador de uma comunidade n\u00f4made, os recabitas.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Onde na B\u00edblia fala de Jonadabe?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Jonadabe \u00e9 uma figura da B\u00edblia Hebraica , aparecendo em 2 Samuel 13. Ele \u00e9 descrito no vers\u00edculo 3 como filho de Simeia , que era irm\u00e3o de Davi, tornando Jonadabe primo de Amnom , bem como seu amigo.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que significa recabitas na palavra de Deus?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Esse tipo de \u201c volta ao passado \u201d ocorre v\u00e1rias vezes no livro de Jeremias. Jeremias 35 fala de um grupo de pessoas chamados recabitas. Eles viviam fora das cidades, em tendas, e nunca se fixavam num lugar. Os recabitas seguiam certas tradi\u00e7\u00f5es estabelecidas pelo l\u00edder de seu grupo.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 Recabe na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Recabe (em hebraico: R\u0113k\u0101b, da raiz para &#8220;carro\u00e7a&#8221; ou &#8220;condutor&#8221;) \u00e9 um personagem b\u00edblico do Antigo Testamento, mencionado como o pai de Jonadabe.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi a m\u00e3e de Joabe?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Zeruia foi uma irm\u00e3 ou talvez meia-irm\u00e3 do rei Davi, e m\u00e3e de Joabe, Abisai e Asael.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Onde est\u00e3o os recabitas hoje?<\/h2>\n\nAinda hoje existem recabitas no Oriente M\u00e9dio. Na Ar\u00e1bia, perto de Meca, foi descoberta uma tribo que se diz descendente de Jonadabe, al\u00e9m de outra, de bedu\u00ednos, perto do Mar Morto. Deus mant\u00e9m Sua promessa h\u00e1 quase 3 mil anos!<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que aconteceu com os recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Eles foram expulsos de seu pa\u00eds pelo rei da Babil\u00f4nia Nabucodonosor e se refugiaram em Jerusal\u00e9m. O senhor ordena ao profeta Jeremias que v\u00e1 aonde moram os Recabitas, converse com eles e os traga at\u00e9 o Templo de Jav\u00e9.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os descendentes dos recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Alguns estudiosos sugerem que mulheres recabitas casaram-se com levitas, e ent\u00e3o descendentes dos recabitas se envolveram com o servi\u00e7o do culto ao Senhor. Antigas tradi\u00e7\u00f5es crist\u00e3s dizem que sacerdotes de ra\u00edzes recabitas oficiavam no tempo do Novo Testamento.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o pa\u00eds dos recabitas?<\/h2>\n\nOs recabitas constitu\u00edam uma comunidade asc\u00e9tica de israelitas contempor\u00e2neos ao profeta Jeremias no Antigo Testamento b\u00edblico.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual era a origem dos recabitas?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os recabitas eram separatistas que se recusavam a participar de atividades agr\u00edcolas, beber vinho ou se envolver em outras pr\u00e1ticas associadas aos cananeus. Acreditando que o estilo de vida semin\u00f4made era uma obriga\u00e7\u00e3o religiosa, eles pastoreavam seus rebanhos por grande parte de Israel e Jud\u00e1.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Por que os recabitas n\u00e3o bebiam vinho?<\/h2>\n\nEles n\u00e3o bebem vinho porque obedecem \u00e0 ordem do seu antepassado.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que Jesus falou sobre beber vinho?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>2) Vejamos a cita\u00e7\u00e3o do vinho no primeiro milagre de Jesus em Can\u00e1 da Galileia: &#8220;e lhe disse: Todos costumam p\u00f4r primeiro o bom vinho e, quando j\u00e1 beberam fartamente, servem o inferior; tu, por\u00e9m, guardaste o bom vinho at\u00e9 agora&#8221;, Jo\u00e3o 2:10.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a explica\u00e7\u00e3o de Jeremias 35?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\u201cPor isso, assim diz o SENHOR dos Ex\u00e9rcitos, o Deus de Israel: Nunca faltar\u00e1 homem a Jonadabe, filho de Recabe, que esteja na Minha presen\u00e7a\u201d (v. 19). O legado deixado atrav\u00e9s da educa\u00e7\u00e3o familiar de fato \u00e9, de toda a ci\u00eancia da educa\u00e7\u00e3o, o maior formador de valores que existe.<br \/>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Quem s\u00e3o os recabitas segundo a B\u00edblia? Esse tipo de \u201cvolta ao passado\u201d ocorre v\u00e1rias vezes no livro de Jeremias. Jeremias 35 fala de um grupo de pessoas chamados recabitas. Eles viviam fora das cidades, em tendas, e nunca se fixavam num lugar. Quem era o povo recabitas na B\u00edblia? Os recabitas eram um grupo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18929","post","type-post","status-publish","format-standard","hentry","category-conteudo"],"_links":{"self":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=18929"}],"version-history":[{"count":1,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18929\/revisions"}],"predecessor-version":[{"id":18930,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18929\/revisions\/18930"}],"wp:attachment":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=18929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=18929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=18929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}