{"id":18777,"date":"2025-08-06T21:25:14","date_gmt":"2025-08-06T21:25:14","guid":{"rendered":"http:\/\/897310e0-3de4-467f-9dba-74c2f088dbbb"},"modified":"2025-08-06T21:25:14","modified_gmt":"2025-08-06T21:25:14","slug":"ou-que-e-na-biblia-o-setenta-vezes-sete","status":"publish","type":"post","link":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/ou-que-e-na-biblia-o-setenta-vezes-sete\/","title":{"rendered":"Ou que \u00e9 na b\u00edblia o setenta vezes sete"},"content":{"rendered":"\n\n<h2 class=\"wp-block-heading\">O que quer dizer 70 vezes 7 na B\u00edblia?<\/h2>\n\nMas Jesus lhe responde com autoridade: \u201cN\u00e3o te digo at\u00e9 sete vezes, mas at\u00e9 setenta vezes sete\u201d, isto \u00e9, sempre, infinitamente ! Sem condi\u00e7\u00f5es nem hesita\u00e7\u00f5es, o disc\u00edpulo de Jesus perdoa sem calcular o n\u00famero de vezes.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que representa o n\u00famero 70 na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>N\u00famero 70: \u2013 Simbolismo B\u00edblico: Setenta \u00e9 frequentemente usado simbolicamente na B\u00edblia para denotar completude, plenitude e universalidade. Exemplos incluem os 70 anci\u00e3os nomeados por Mois\u00e9s (Nm 11:16-17), as 70 na\u00e7\u00f5es descendentes de No\u00e9 (Gn 10) e os 70 membros da fam\u00edlia de Jac\u00f3 que foram para o Egito (\u00cax 1:5).<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9 70 vezes 7 a medida do perd\u00e3o?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Jesus nos ensinou a perdoar 70 vezes 7, ou seja, infinitamente. O perd\u00e3o n\u00e3o \u00e9 sobre o outro, mas sobre libertar o nosso pr\u00f3prio cora\u00e7\u00e3o da m\u00e1goa e do ressentimento. Se Deus nos perdoa todos os dias, por que n\u00f3s n\u00e3o far\u00edamos o mesmo? Liberte-se, ame mais e deixe a paz reinar em sua vida!<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que Jesus quis dizer quando respondeu a Pedro que devemos perdoar setenta vezes sete?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Pedro j\u00e1 \u00e9 misericordioso, porque, na verdade, n\u00e3o \u00e9 f\u00e1cil perdoar sete vezes o mesmo pecado ao mesmo ofensor. Mas Jesus lhe responde com autoridade: \u201cN\u00e3o te digo at\u00e9 sete vezes, mas at\u00e9 setenta vezes sete\u201d, isto \u00e9, sempre, infinitamente !<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que significa tatuar 70&#215;7?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Voc\u00ea j\u00e1 viu uma tatuagem com \u201c70&#215;7\u201d? Esse s\u00edmbolo vai muito al\u00e9m dos n\u00fameros. Ele carrega uma mensagem profunda baseada na B\u00edblia, no Evangelho de Mateus (18:22), onde Jesus nos ensina sobre o perd\u00e3o sem limites. \u201cSetenta vezes sete\u201d representa um ciclo cont\u00ednuo de renova\u00e7\u00e3o, miseric\u00f3rdia e crescimento espiritual.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quantas vezes os judeus perdoavam?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os judeus perdoavam tr\u00eas vezes, o ap\u00f3stolo Pedro acrescentou um pouco mais do dobro. Entretanto, Jesus ensinou que devemos perdoar \u201csetenta vezes sete\u201d, quer dizer sempre, infinitas vezes. O perd\u00e3o n\u00e3o \u00e9 esquecer o ocorrido, n\u00e3o \u00e9 um sentimento, mas \u00e9 uma decis\u00e3o de perdoar quem me feriu.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o significado da par\u00e1bola de 70&#215;7 vezes?<\/h2>\n\nDepois de dizer que devemos perdoar 70&#215;7 vezes, Jesus contou uma par\u00e1bola sobre um homem que devia muito dinheiro ao seu patr\u00e3o. Ele devia tanto que nunca poderia pagar, nem se tivesse v\u00e1rias vidas! O homem implorou por miseric\u00f3rdia e seu patr\u00e3o perdoou a d\u00edvida.<br \/>\n<h3>Perdoar 70x7: significado e explica\u00e7\u00e3o.<\/h3><iframe src=\"https:\/\/www.youtube.com\/embed\/JVLM0_b7Oxg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n\n\n\n\n\n<h2 class=\"wp-block-heading\">O que Jesus quis dizer com a express\u00e3o 70 vezes 7?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Pedro j\u00e1 \u00e9 misericordioso, porque, na verdade, n\u00e3o \u00e9 f\u00e1cil perdoar sete vezes o mesmo pecado ao mesmo ofensor. Mas Jesus lhe responde com autoridade: \u201cN\u00e3o te digo at\u00e9 sete vezes, mas at\u00e9 setenta vezes sete\u201d, isto \u00e9, sempre, infinitamente!<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o significado da par\u00e1bola de 70&#215;7?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Mas Jesus lhe responde com autoridade: \u201cN\u00e3o te digo at\u00e9 sete vezes, mas at\u00e9 setenta vezes sete\u201d, isto \u00e9, sempre, infinitamente! Sem condi\u00e7\u00f5es nem hesita\u00e7\u00f5es, o disc\u00edpulo de Jesus perdoa sem calcular o n\u00famero de vezes.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o verdadeiro significado de perd\u00e3o?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>O perd\u00e3o \u00e9 uma oportunidade para se libertar de amarras negativas do passado e seguir adiante. Sendo assim, perdoar \u00e9 uma a\u00e7\u00e3o libertadora que simboliza a intelig\u00eancia e permite o amadurecimento de uma pessoa. N\u00e3o perdoar impede a chance de viver novas possibilidades e ter mais satisfa\u00e7\u00e3o na vida pessoal.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o significado da tatuagem 70&#215;7?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>70&#215;7: em palavras simples representa o perd\u00e3o ou a capacidade infinita de perdoar.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que nos ensina a par\u00e1bola do perd\u00e3o?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A par\u00e1bola do perd\u00e3o ensina que devemos perdoar sempre, sem limites, assim como Deus nos perdoa. Nela, um rei perdoa uma grande d\u00edvida de um devedor, mas este se recusa a perdoar uma pequena d\u00edvida de um conhecido.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o significado do n\u00famero 70 na B\u00edblia?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">O que a B\u00edblia fala sobre 70?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A dura\u00e7\u00e3o da nossa vida \u00e9 de setenta anos ; e se alguns, pela sua robustez, chegam a oitenta anos, a medida deles \u00e9 canseira e enfado; pois passa rapidamente, e n\u00f3s voamos.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os 70 na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Os 70 s\u00e3o aqueles que s\u00e3o enviados em pares em Lucas 10. Ent\u00e3o, se voc\u00ea acredita na B\u00edblia, ou pelo menos reconhece sua historicidade, \u00e9 claro que \u00e9 verdade.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 a miss\u00e3o dos 70 na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>A miss\u00e3o dos setenta disc\u00edpulos corresponde \u00e0 miss\u00e3o da igreja nos dias de hoje. Da mesma forma como o Senhor enviou aqueles disc\u00edpulos, Ele tamb\u00e9m nos enviou com a mesma miss\u00e3o, os mesmos objetivos e as mesmas precau\u00e7\u00f5es que os setenta deveriam tomar. N\u00f3s tamb\u00e9m vivemos &#8220;como cordeiros ao meio de lobos&#8221;.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a explica\u00e7\u00e3o de Mateus 18:21?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Leia Mateus 18:21-35<\/li>\n<li> Em primeiro lugar, perdoar os outros, quando eles nos fazem mal, faz parte da nossa gratid\u00e3o a Deus por ter perdoado os nossos pecados atrav\u00e9s da morte de Jesus na cruz. O perd\u00e3o de Deus baseia-se exclusivamente no seu amor e na sua gra\u00e7a incondicional. N\u00f3s n\u00e3o o merecemos.<\/li>\n<\/ul>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que podemos aprender com Mateus 18:21?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Uma verdade que podemos aprender com esta par\u00e1bola \u00e9 que podemos seguir o exemplo de Jesus Cristo perdoando as outras pessoas, assim como Ele nos perdoa. O Senhor reiterou a import\u00e2ncia de perdoar as outras pessoas em nossa dispensa\u00e7\u00e3o.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que significa perdoar setenta vezes sete?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Ao dizer 70&#215;7, Jesus estava usando uma express\u00e3o hebraica que simboliza um n\u00famero infinito de vezes. Ele nos mostra que devemos perdoar nossos irm\u00e3os e irm\u00e3s repetidamente, sem limites, assim como Deus nos perdoa. Perdoar n\u00e3o significa esquecer ou tolerar o mal, mas \u00e9 um ato de amor, compaix\u00e3o e miseric\u00f3rdia.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que Jesus quis dizer no cap\u00edtulo 18 de Mateus?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>RESUMO: Em Mateus 18:18, Jesus disse que tudo que a Igreja \u201cligasse\u201d ou \u201cdesligasse\u201d na Terra, o mesmo se daria no C\u00e9u. Essa autoridade de que trata o texto tem recebido v\u00e1rias interpreta\u00e7\u00f5es: (1) seria uma autoridade de estabelecer doutrinas; (2) de perdoar pecados; ou (3) aplicar disciplina eclesi\u00e1stica.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Porque 70 vezes 7 \u00e9 infinito?<\/h2>\n\nAo dizer 70&#215;7, Jesus estava usando uma express\u00e3o hebraica que simboliza um n\u00famero infinito de vezes. Ele nos mostra que devemos perdoar nossos irm\u00e3os e irm\u00e3s repetidamente, sem limites, assim como Deus nos perdoa.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Porque 70&#215;7 \u00e9 infinito?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>Ao dizer 70&#215;7, Jesus estava usando uma express\u00e3o hebraica que simboliza um n\u00famero infinito de vezes. Ele nos mostra que devemos perdoar nossos irm\u00e3os e irm\u00e3s repetidamente, sem limites, assim como Deus nos perdoa.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a explica\u00e7\u00e3o de Mateus 18:22?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>O que o Salvador quis dizer quando disse a Pedro para perdoar \u00e0s pessoas \u201cat\u00e9 setenta vezes sete\u201d? ( Mateus 18:22) O Salvador basicamente disse a Pedro para nem mesmo contar \u2014 a fim de n\u00e3o estabelecer limites para o perd\u00e3o.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">O que significa o n\u00famero 7 na B\u00edblia?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o significado do nome 7 na B\u00edblia?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>G\u00eanesis 5:4 diz que Ad\u00e3o gerou &#8220;filhos e filhas&#8221; antes de sua morte, com idade de 930 anos. Afirma-se em G\u00eanesis 4:25 que o nome Sete significa &#8220;concedido&#8221;.<br \/>\n\n\n\n\n<h2 class=\"wp-block-heading\">Por que o n\u00famero 7 \u00e9 especial?<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><\/p>O Seten\u00e1rio, o poderoso n\u00famero 7 (sete) \u00e9 o n\u00famero representativo da harmonia, resultante do equil\u00edbrio, estabelecido por elementos n\u00e3o semelhantes. Na interpreta\u00e7\u00e3o dos n\u00fameros, o 7 \u00e9 considerado uma situa\u00e7\u00e3o especial em rela\u00e7\u00e3o aos demais.<br \/>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O que quer dizer 70 vezes 7 na B\u00edblia? Mas Jesus lhe responde com autoridade: \u201cN\u00e3o te digo at\u00e9 sete vezes, mas at\u00e9 setenta vezes sete\u201d, isto \u00e9, sempre, infinitamente ! Sem condi\u00e7\u00f5es nem hesita\u00e7\u00f5es, o disc\u00edpulo de Jesus perdoa sem calcular o n\u00famero de vezes. O que representa o n\u00famero 70 na B\u00edblia? N\u00famero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18777","post","type-post","status-publish","format-standard","hentry","category-conteudo"],"_links":{"self":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=18777"}],"version-history":[{"count":1,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18777\/revisions"}],"predecessor-version":[{"id":18778,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/18777\/revisions\/18778"}],"wp:attachment":[{"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=18777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=18777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ammabarbacena.com.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=18777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}